{"id":12901,"date":"2022-06-22T09:03:00","date_gmt":"2022-06-22T07:03:00","guid":{"rendered":"https:\/\/www.thegreenbow.com\/?post_type=resource&#038;p=12901"},"modified":"2022-10-17T09:10:44","modified_gmt":"2022-10-17T07:10:44","slug":"connaissez-vous-le-mode-filtrant-du-client-vpn-windows","status":"publish","type":"resource","link":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/","title":{"rendered":"Connaissez-vous le Mode filtrant du Client VPN Windows ?"},"content":{"rendered":"\n<div class=\"wp-block-ch-resource-content alignfull\">\n<p><strong>Auteur : Arnaud Dufournet, Chief Marketing Officer<\/strong><\/p>\n\n\n\n<p>Le travail hybride devient la nouvelle norme dans les entreprises. Quatre entreprises sur cinq ont adopt\u00e9 une organisation dite \u00ab\u00a0hybride\u00a0\u00bb. C\u2019est-\u00e0-dire qu\u2019elles proposent \u00e0 leurs salari\u00e9s d\u2019alterner la pr\u00e9sence au bureau avec le t\u00e9l\u00e9travail. Deux jours t\u00e9l\u00e9travaill\u00e9s par semaine est la moyenne constat\u00e9e par une \u00e9tude men\u00e9e (<a href=\"https:\/\/www.andrh.fr\/uploads\/files\/attachments\/622b046587abf003039119.pdf\"><em>Le futur du travail vu par les DRH<\/em>, 2e \u00e9dition, mars 2022<\/a>) conjointement par le Boston Consulting Group et l&rsquo;Association Nationale des DRH. Mais cette nouvelle organisation de travailler est loin d\u2019\u00eatre sans risque pour la cybers\u00e9curit\u00e9 des entreprises. Elle donne m\u00eame de plus en plus de sueurs froides aux responsables de la s\u00e9curit\u00e9 des syst\u00e8mes d\u2019information (RSSI).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Les usages num\u00e9riques \u00e0 risque se d\u00e9veloppent<\/strong><\/strong><\/h2>\n\n\n\n<p>Le travail hybride am\u00e8ne beaucoup de flexibilit\u00e9 mais favorise aussi les usages num\u00e9riques \u00e0 risque. Les usages personnels et professionnels des \u00e9quipements du salari\u00e9s (t\u00e9l\u00e9phone et ordinateur) se confondent bien souvent.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:41% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-1024x684.jpeg\" alt=\"\" class=\"wp-image-12904 size-full\" srcset=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-1024x684.jpeg 1024w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-300x200.jpeg 300w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-768x513.jpeg 768w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-1536x1025.jpeg 1536w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-100x67.jpeg 100w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-301x201.jpeg 301w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite-343x229.jpeg 343w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Nomadisme_Lite.jpeg 1772w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Une pratique reconnue par 55 % des t\u00e9l\u00e9travailleurs dans le monde selon une \u00e9tude men\u00e9e par Gartner (<a href=\"https:\/\/www.gartner.com\/en\/newsroom\/press-releases\/2021-04-26-gartner-survey-finds-1-in-5-workers-consider-themselves-digital-technology-experts-since-covid-19\">Gartner 2021 Digital Worker Experience Survey<\/a>). <\/p>\n\n\n\n<p>Ces nouvelles vuln\u00e9rabilit\u00e9s sont particuli\u00e8rement cibl\u00e9es par les hackers et notamment les \u00e9quipements mobiles. <\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Selon Nokia (<a href=\"https:\/\/nam12.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fpages.nokia.com%2FT006US-Threat-Intelligence-Report-2021.html&amp;data=04%7C01%7C%7C03f66ee34d8242f62f2808da13ea3d67%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637844194015773544%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000&amp;sdata=2tRksdQatMC6Euspsoq%2FOCdU2mcRaWzOYEc8%2FoUM3ig%3D&amp;reserved=0\">Rappo<\/a><a href=\"https:\/\/pages.nokia.com\/T006US-Threat-Intelligence-Report-2021.html\" target=\"_blank\" rel=\"noreferrer noopener\">rt threat intelligence Nokia<\/a>) , 0,12 % de tous les appareils mobiles dans le monde sont infect\u00e9s par des logiciels malveillants chaque mois. Sur 5 milliards de mobiles dans le monde, cela repr\u00e9sente 6 millions de mobiles infect\u00e9s tous les mois&nbsp;!<\/p>\n\n\n\n<p>Toutes les tailles d\u2019entreprises sont concern\u00e9es par ces attaques visant les terminaux mobiles. Les pi\u00e8ges tendus par les pirates sont tr\u00e8s divers&nbsp;: les plus courants sont les emails de phishing mais le smishing (arnaque par SMS) se d\u00e9veloppe aussi beaucoup. Dans la palette des armes employ\u00e9es par les pirates, on trouve \u00e9galement la compromission des terminaux par les Wi-Fi domestiques ou publics g\u00e9n\u00e9ralement moins s\u00e9curis\u00e9s et les malwares mobiles charg\u00e9s via de fausses applications sur des stores d\u00e9tourn\u00e9s. Enfin, les vuln\u00e9rabilit\u00e9s pr\u00e9sentes dans les navigateurs web sont \u00e9galement exploit\u00e9es.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>S\u00e9curiser les travailleurs distants reste un d\u00e9fi majeur<\/strong><\/strong><\/h2>\n\n\n\n<p>En 2021, 65&nbsp;% des organisations ont constat\u00e9 une augmentation significative des tentatives de cyberattaques, ce qui est particuli\u00e8rement probl\u00e9matique puisque 78&nbsp;% affirment que les t\u00e9l\u00e9travailleurs sont plus difficiles \u00e0 s\u00e9curiser selon une \u00e9tude mondiale de Splunk Splunk (<a href=\"https:\/\/www.splunk.com\/fr_fr\/form\/state-of-security.html\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9tat de la cybers\u00e9curit\u00e9 en 2022<\/a>) aupr\u00e8s de 1200 responsables de la cybers\u00e9curit\u00e9. Dans cette m\u00eame \u00e9tude, 64&nbsp;% des personnes interrog\u00e9es admettent \u00e9galement que le respect des exigences de s\u00e9curit\u00e9 est devenu plus difficile ces derni\u00e8res ann\u00e9es.<\/p>\n\n\n\n<p>Alors qu\u2019il est commun\u00e9ment admis qu\u2019une erreur humaine est \u00e0 l\u2019origine de 95 % des attaques r\u00e9ussies, les mauvaises pratiques ont pourtant la peau dure. Par exemple, seuls 31 % des employ\u00e9s pensent que le fait de laisser leurs amis et leur famille utiliser leur appareil professionnel pr\u00e9sente un risque de s\u00e9curit\u00e9.&nbsp; Les professionnels de l\u2019information ne sont gu\u00e8re plus raisonnables puisque 40 % d\u2019entre eux reconnaissent avoir recours \u00e0 du \u201cShadow IT\u201d c\u2019est \u00e0 dire \u00e0 des applications ou syst\u00e8mes de communication informatique non autoris\u00e9s officiellement par la direction informatique.<\/p>\n\n\n\n<p>Toutes ces pratiques sont autant de faiblesses exploit\u00e9es par les cybercriminels pour s\u2019introduire dans le SI, voler des informations sensibles, bloquer les syst\u00e8mes par des attaques de ransomware, ou encore espionner, etc. Les impacts financiers et sur la r\u00e9putation peuvent alors \u00eatre d\u00e9sastreux.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:37% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-1024x683.jpeg\" alt=\"\" class=\"wp-image-12912 size-full\" srcset=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-1024x683.jpeg 1024w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-300x200.jpeg 300w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-768x512.jpeg 768w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-1536x1024.jpeg 1536w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-100x67.jpeg 100w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-301x201.jpeg 301w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite-343x229.jpeg 343w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/BurnOut_lite.jpeg 1773w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Plus inqui\u00e9tant encore, les \u00e9quipes charg\u00e9es de la Cybers\u00e9curit\u00e9 montrent elles-m\u00eames des signes de faiblesse du fait des responsabilit\u00e9s et de la charge de travail qui p\u00e8sent sur elles. Dans l\u2019\u00e9tude Splunk, on apprend que 73&nbsp;% des RSSI interrog\u00e9s ont assist\u00e9 \u00e0 des d\u00e9missions de coll\u00e8gues suite \u00e0 un burn out. Ils sont 70 % \u00e0 d\u00e9clarer que l\u2019augmentation de la charge de travail qui en r\u00e9sulte les a incit\u00e9s \u00e0 envisager de changer de poste. <\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>La Grande D\u00e9mission planerait elle aussi sur la cybers\u00e9curit\u00e9&nbsp;?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>R\u00e9duire les surfaces d\u2019attaque avec le mode filtrant<\/strong><\/strong><\/h2>\n\n\n\n<p>Il y a urgence \u00e0 donner les moyens aux RSSI de reprendre le contr\u00f4le et d\u2019accomplir leur mission si critique pour la survie d\u2019une organisation. Face au d\u00e9fi de la s\u00e9curisation des connexions distantes au r\u00e9seau de l\u2019entreprise, ils ont besoin de solution permettant de regagner en maitrise sur leur parc informatique. C\u2019est exactement l\u2019objectif du mode filtrant propos\u00e9 avec le Client VPN Windows TheGreenBow.<\/p>\n\n\n\n<p>Cette fonction orient\u00e9e ZTNA (<a href=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/quatre-idees-recues-sur-zero-trust\/\">Zero Trust Network  Access<\/a>) et totalement transparente pour l\u2019utilisateur, permet de filtrer les flux de communication du poste de travail dans le but de r\u00e9duire consid\u00e9rablement la surface d\u2019attaque.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 35%\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-1024x683.jpeg\" alt=\"\" class=\"wp-image-12908 size-full\" srcset=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-1024x683.jpeg 1024w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-300x200.jpeg 300w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-768x512.jpeg 768w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-1536x1024.jpeg 1536w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-100x67.jpeg 100w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-301x201.jpeg 301w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-343x229.jpeg 343w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-727x486.jpeg 727w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-602x402.jpeg 602w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite-686x458.jpeg 686w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite.jpeg 1773w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Une fois param\u00e9tr\u00e9e, cette fonctionnalit\u00e9 prot\u00e8ge le poste de travail en r\u00e9duisant <strong>au strict minimum les flux entrants et sortants autoris\u00e9s<\/strong>. Le mode filtrant emp\u00eache l\u2019envoi de donn\u00e9es non voulu depuis le poste comme peut le faire par exemple un Keylogger, ou bien l\u2019ex\u00e9cution de codes malveillants.<\/p>\n<\/div><\/div>\n\n\n\n<p>Et ce n\u2019est pas tout, l\u2019autorisation des flux est contextualis\u00e9e en fonction de la posture du poste de travail. Concr\u00e8tement, des jeux de r\u00e8gles diff\u00e9rents sont applicables si le poste est par exemple en situation de nomadisme ou bien connect\u00e9 au r\u00e9seau de l\u2019entreprise.<\/p>\n\n\n\n<p>Autre avantage de taille&nbsp;: le mode filtrant d\u00e9marre d\u00e8s l\u2019ouverture du poste avant m\u00eame l\u2019ouverture d\u2019une cession Windows pour que la protection du poste s\u2019active imm\u00e9diatement.<\/p>\n\n\n\n<p>Le mode filtrant est disponible avec l\u2019<strong>\u00e9dition Enterprise du Client VPN Windows TheGreenBow<\/strong>. Si vous souhaitez en savoir plus, n&rsquo;h\u00e9sitez pas \u00e0 demander une d\u00e9monstration \u00e0 nos \u00e9quipes. En cliquant sur le lien ci-dessous, vous pouvez \u00e9galement revoir une d\u00e9monstration r\u00e9alis\u00e9e lors du webinaire consacr\u00e9 aux fonctionnalit\u00e9s avanc\u00e9es du Client VPN Windows Enterprise.<\/p>\n\n\n\n<p><\/p>\n\n\n\n  <section  class=\"wp-block-acf-linked-pages  section-content linked-pages-section\"  itemprop=\"hasPart\" itemscope itemtype=\"https:\/\/schema.org\/WebPageElement\">\n    <div class=\"grid-container\">\n     <div class=\"grid-x grid-padding-x align-center mobile-slider\">\n                <div class=\"cell medium-4 article\">\n            <div class=\"wrapper\">\n              \n                              <a  href=\"https:\/\/www.thegreenbow.com\/fr\/contact\/\" >\n\n                                          <figure>\n                        <img decoding=\"async\"  data-fade-in loading=\"lazy\" src=\"data:image\/png;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" data-lazy-interchange=\"[https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-727x486.jpeg, small], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-301x201.jpeg, medium], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-343x229.jpeg, large], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-1454x972.jpeg, retina], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-602x402.jpeg, medium_retina], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-686x458.jpeg, large_retina]\" data-interchange-sizes=\"{&quot;small&quot;:{&quot;w&quot;:727,&quot;h&quot;:486},&quot;medium&quot;:{&quot;w&quot;:301,&quot;h&quot;:201},&quot;large&quot;:{&quot;w&quot;:343,&quot;h&quot;:229},&quot;retina&quot;:{&quot;w&quot;:1454,&quot;h&quot;:972},&quot;medium_retina&quot;:{&quot;w&quot;:602,&quot;h&quot;:402},&quot;large_retina&quot;:{&quot;w&quot;:686,&quot;h&quot;:458}}\"  alt=\"Connaissez-vous le Mode filtrant du Client VPN Windows ?\" itemprop=\"image\" data-fade-in \/>\n                      <\/figure>\n                    \n                                      <h4 class=\"block-title\">Demander votre d\u00e9mo<\/h4>\n                  \n                  \n                <\/a>\n              \n            <\/div>\n          <\/div>\n\n                  <div class=\"cell medium-4 article\">\n            <div class=\"wrapper\">\n              \n                              <a  href=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/webinaire\/decouvrez-les-fonctionnalites-du-client-vpn-thegreenbow-windows-enterprise\/\" >\n\n                                          <figure>\n                        <img decoding=\"async\"  data-fade-in loading=\"lazy\" src=\"data:image\/png;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" data-lazy-interchange=\"[https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-727x486.jpeg, small], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-301x201.jpeg, medium], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-343x229.jpeg, large], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-1454x972.jpeg, retina], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-602x402.jpeg, medium_retina], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/05\/Header_Produits-686x458.jpeg, large_retina]\" data-interchange-sizes=\"{&quot;small&quot;:{&quot;w&quot;:727,&quot;h&quot;:486},&quot;medium&quot;:{&quot;w&quot;:301,&quot;h&quot;:201},&quot;large&quot;:{&quot;w&quot;:343,&quot;h&quot;:229},&quot;retina&quot;:{&quot;w&quot;:1454,&quot;h&quot;:972},&quot;medium_retina&quot;:{&quot;w&quot;:602,&quot;h&quot;:402},&quot;large_retina&quot;:{&quot;w&quot;:686,&quot;h&quot;:458}}\"  alt=\"Connaissez-vous le Mode filtrant du Client VPN Windows ?\" itemprop=\"image\" data-fade-in \/>\n                      <\/figure>\n                    \n                                      <h4 class=\"block-title\">Revoir le webinaire<\/h4>\n                  \n                  \n                <\/a>\n              \n            <\/div>\n          <\/div>\n\n        \n\t\t<\/div>\n    <\/div>\n  <\/section>\n<\/div>\n","protected":false},"featured_media":12908,"template":"","meta":{"_acf_changed":false,"resource_type":"internal"},"resource_category":[30],"class_list":["post-12901","resource","type-resource","status-publish","has-post-thumbnail","hentry","resource_category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Connaissez-vous le Mode filtrant du Client VPN Windows ? - TheGreenBow<\/title>\n<meta name=\"description\" content=\"Le travail hybride rend compliqu\u00e9 la s\u00e9curisation de vos postes de travail ? D\u00e9couvrez le mode filtrant du Client VPN ThegGreenBow !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Connaissez-vous le Mode filtrant du Client VPN Windows ? - TheGreenBow\" \/>\n<meta property=\"og:description\" content=\"Le travail hybride rend compliqu\u00e9 la s\u00e9curisation de vos postes de travail ? D\u00e9couvrez le mode filtrant du Client VPN ThegGreenBow !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/\" \/>\n<meta property=\"og:site_name\" content=\"TheGreenBow\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-17T07:10:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1773\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@thegreenbow\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/\",\"name\":\"Connaissez-vous le Mode filtrant du Client VPN Windows ? - TheGreenBow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Mode-filtrant_lite.jpeg\",\"datePublished\":\"2022-06-22T07:03:00+00:00\",\"dateModified\":\"2022-10-17T07:10:44+00:00\",\"description\":\"Le travail hybride rend compliqu\u00e9 la s\u00e9curisation de vos postes de travail ? D\u00e9couvrez le mode filtrant du Client VPN ThegGreenBow !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Mode-filtrant_lite.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Mode-filtrant_lite.jpeg\",\"width\":1773,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressources\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Connaissez-vous le Mode filtrant du Client VPN Windows ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/\",\"name\":\"TheGreenBow\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#organization\",\"name\":\"TheGreenBow\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logotype@2x-min.png\",\"contentUrl\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logotype@2x-min.png\",\"width\":422,\"height\":84,\"caption\":\"TheGreenBow\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/thegreenbow\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/thegreenbow\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZKtI7_fmgFcmovgGSy8AnQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Connaissez-vous le Mode filtrant du Client VPN Windows ? - TheGreenBow","description":"Le travail hybride rend compliqu\u00e9 la s\u00e9curisation de vos postes de travail ? D\u00e9couvrez le mode filtrant du Client VPN ThegGreenBow !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/","og_locale":"fr_FR","og_type":"article","og_title":"Connaissez-vous le Mode filtrant du Client VPN Windows ? - TheGreenBow","og_description":"Le travail hybride rend compliqu\u00e9 la s\u00e9curisation de vos postes de travail ? D\u00e9couvrez le mode filtrant du Client VPN ThegGreenBow !","og_url":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/","og_site_name":"TheGreenBow","article_modified_time":"2022-10-17T07:10:44+00:00","og_image":[{"width":1773,"height":1182,"url":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@thegreenbow","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/","url":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/","name":"Connaissez-vous le Mode filtrant du Client VPN Windows ? - TheGreenBow","isPartOf":{"@id":"https:\/\/www.thegreenbow.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/#primaryimage"},"image":{"@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite.jpeg","datePublished":"2022-06-22T07:03:00+00:00","dateModified":"2022-10-17T07:10:44+00:00","description":"Le travail hybride rend compliqu\u00e9 la s\u00e9curisation de vos postes de travail ? D\u00e9couvrez le mode filtrant du Client VPN ThegGreenBow !","breadcrumb":{"@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/#primaryimage","url":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite.jpeg","contentUrl":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/06\/Mode-filtrant_lite.jpeg","width":1773,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/connaissez-vous-le-mode-filtrant-du-client-vpn-windows\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thegreenbow.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.thegreenbow.com\/fr\/ressources\/blog\/"},{"@type":"ListItem","position":3,"name":"Connaissez-vous le Mode filtrant du Client VPN Windows ?"}]},{"@type":"WebSite","@id":"https:\/\/www.thegreenbow.com\/fr\/#website","url":"https:\/\/www.thegreenbow.com\/fr\/","name":"TheGreenBow","description":"","publisher":{"@id":"https:\/\/www.thegreenbow.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thegreenbow.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thegreenbow.com\/fr\/#organization","name":"TheGreenBow","url":"https:\/\/www.thegreenbow.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thegreenbow.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/04\/Logotype@2x-min.png","contentUrl":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/04\/Logotype@2x-min.png","width":422,"height":84,"caption":"TheGreenBow"},"image":{"@id":"https:\/\/www.thegreenbow.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/thegreenbow","https:\/\/fr.linkedin.com\/company\/thegreenbow","https:\/\/www.youtube.com\/channel\/UCZKtI7_fmgFcmovgGSy8AnQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/resource\/12901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/media\/12908"}],"wp:attachment":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/media?parent=12901"}],"wp:term":[{"taxonomy":"resource_category","embeddable":true,"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/resource_category?post=12901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}