{"id":14668,"date":"2023-01-03T14:13:34","date_gmt":"2023-01-03T12:13:34","guid":{"rendered":"https:\/\/www.thegreenbow.com\/?post_type=resource&#038;p=14668"},"modified":"2023-10-19T09:19:28","modified_gmt":"2023-10-19T07:19:28","slug":"reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier","status":"publish","type":"resource","link":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/","title":{"rendered":"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier"},"content":{"rendered":"\n<div class=\"wp-block-ch-resource-content alignfull\">\n<p><strong>Auteur : Arnaud Dufournet<\/strong>, Chief Marketing Officer<\/p>\n\n\n\n<p>Nous avions annonc\u00e9 dans notre <a href=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/que-nous-reserve-leurope-en-matiere-de-reglementations-cyber\/\">premier blog post de l\u2019ann\u00e9e 2022<\/a> que l\u2019actualit\u00e9 sur les r\u00e9glementations cyber en Europe serait riche. Nous n\u2019avons pas \u00e9t\u00e9 d\u00e9mentis. Tout s\u2019est subitement acc\u00e9l\u00e9r\u00e9 sur les deux derniers mois de 2022 avec l\u2019adoption de la nouvelle Directive NIS et du R\u00e8glement DORA par le Parlement Europ\u00e9en puis par le Conseil de l\u2019Union Europ\u00e9enne fin novembre. Et c\u2019est finalement le 27 d\u00e9cembre que la nouvelle directive et le r\u00e8glement ont \u00e9t\u00e9 officiellement publi\u00e9s au Journal Officiel de l\u2019UE, donnant ainsi plus de visibilit\u00e9 sur le calendrier de leur mise en application.<\/p>\n\n\n\n<p>Pour rappel le <strong><a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/FR\/TXT\/PDF\/?uri=CELEX:32022R2554\" target=\"_blank\" rel=\"noreferrer noopener\">Digital Operational Resilience Act<\/a><\/strong> (DORA) est un r\u00e8glement europ\u00e9en qui est une d\u00e9clinaison sectorielle de la directive NIS pour le secteur financier. Ce secteur est un habitu\u00e9 des r\u00e9glementations mais ce nouveau r\u00e8glement se r\u00e9v\u00e8le particuli\u00e8rement exigeant notamment en ce qui concerne la relation contractuelle avec les prestataires de services informatiques.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>La gen\u00e8se de DORA&nbsp;: le risque op\u00e9rationnel<\/strong><\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p>La crise financi\u00e8re de 2008 a mis en \u00e9vidence l\u2019interconnexion et les d\u00e9pendances entre les banques et les assureurs. C\u2019est pour se pr\u00e9munir du risque op\u00e9rationnel que les accords de B\u00e2le II puis B\u00e2le III ont vu le jour. En 2010, B\u00e2le III a renforc\u00e9 les r\u00e8gles prudentielles pour limiter le risque de cr\u00e9dit mais pas seulement \u2026<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:43% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"659\" src=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risk_Lite-1024x659.jpeg\" alt=\"\" class=\"wp-image-14670 size-full\" srcset=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risk_Lite-1024x659.jpeg 1024w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risk_Lite-300x193.jpeg 300w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risk_Lite-768x494.jpeg 768w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risk_Lite-1536x988.jpeg 1536w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risk_Lite-100x64.jpeg 100w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risk_Lite.jpeg 1805w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Il a \u00e9galement introduit l&rsquo;inclusion des&nbsp;risques op\u00e9rationnels&nbsp;dans l&rsquo;\u00e9valuation des exigences minimales de fonds propres. Un risque op\u00e9rationnel selon la d\u00e9finition du comit\u00e9 de B\u00e2le, est un risque de pertes r\u00e9sultant \u00ab&nbsp;<em>de processus, de personnes et de syst\u00e8mes bancaires internes inad\u00e9quats, d\u00e9faillants ou encore d&rsquo;\u00e9v\u00e9nements externes<\/em>&nbsp;\u00bb.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Cette d\u00e9finition, tr\u00e8s large, englobe la d\u00e9faillance des syst\u00e8mes d\u2019information. Or ceux-ci ont pris une place de plus en plus importante avec la num\u00e9risation des processus et le recours aux nouvelles technologies (IA, RPA, Cloud, \u2026). La crise de 2008 a montr\u00e9 que la d\u00e9faillance des syst\u00e8mes d\u2019information doit faire pleinement partie des risques op\u00e9rationnels et syst\u00e9miques.<\/p>\n\n\n\n<p>Ces derni\u00e8res ann\u00e9es, l\u2019augmentation de la menace cyber est venue renforcer ce risque de d\u00e9faillance. Les causes ne sont plus simplement techniques ou dues \u00e0 l\u2019erreur humaine. Elles peuvent provenir d\u2019une malveillance prenant la forme de cyber attaque d\u2019origine criminelle ou \u00e9tatique pour du renseignement \u00e9conomique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>Les menaces cyber se renforcent, le risque op\u00e9rationnel aussi<\/strong><\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:36% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"733\" height=\"600\" src=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risque-systemique_rapport-BDF-1.jpg\" alt=\"\" class=\"wp-image-14678 size-full\" srcset=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risque-systemique_rapport-BDF-1.jpg 733w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risque-systemique_rapport-BDF-1-300x246.jpg 300w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Risque-systemique_rapport-BDF-1-100x82.jpg 100w\" sizes=\"auto, (max-width: 733px) 100vw, 733px\" \/><figcaption>Source : Banque Centrale Europ\u00e9enne<\/figcaption><\/figure><div class=\"wp-block-media-text__content\">\n<p>Le risque cyber est d\u00e9sormais bien identifi\u00e9 et suivi par la Banque de France et la Banque Centrale Europ\u00e9enne en figurant parmi l\u2019ensemble des risques syst\u00e9miques. Nous l\u2019avions d\u2019ailleurs d\u00e9j\u00e0 abord\u00e9 dans <a href=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/pourquoi-le-secteur-bancaire-et-financier-prend-il-la-menace-cyber-tres-au-serieux\/\" target=\"_blank\" rel=\"noreferrer noopener\">un pr\u00e9c\u00e9dent blog post<\/a> consacr\u00e9 au secteur bancaire.<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Les transactions bancaires passant par les r\u00e9seaux et les masses de donn\u00e9es personnelles manipul\u00e9es sont les principaux centres d\u2019int\u00e9r\u00eat des cybercriminels. L\u2019\u00e9tude d\u2019IBM x-Force Threat Intelligence Index 2022 r\u00e9v\u00e8le une nouvelle fois que le secteur financier est bien l\u2019un des secteurs les plus attaqu\u00e9s, juste apr\u00e8s l\u2019industrie manufacturi\u00e8re. <\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p>Selon cette \u00e9tude, le secteur financier concentrerait 22% des attaques et incidents relev\u00e9s en 2021. Ces attaques visant surtout les banques (70% des attaques contre 16% pour les assurances).<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"841\" height=\"649\" src=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/IBM-xForce-study.png\" alt=\"\" class=\"wp-image-14682 size-full\" srcset=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/IBM-xForce-study.png 841w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/IBM-xForce-study-300x232.png 300w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/IBM-xForce-study-768x593.png 768w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/IBM-xForce-study-100x77.png 100w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure><\/div>\n\n\n\n<p>Ce qui est maintenant en jeu, c\u2019est un possible effondrement du syst\u00e8me bancaire et donc de nos \u00e9conomies. L\u2019Union Europ\u00e9enne l\u2019a bien compris et a d\u00e9cid\u00e9 prendre le sujet \u00e0 bras le corps en approfondissant la notion de risque op\u00e9rationnel num\u00e9rique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong><strong>Apr\u00e8s NIS 2 voici donc DORA<\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p>Dans le sillage de la directive NIS dont la premi\u00e8re version a \u00e9t\u00e9 ent\u00e9rin\u00e9e en 2016, les premi\u00e8res r\u00e9flexions de la Commission Europ\u00e9enne commence en 2020 sur un r\u00e8glement d\u00e9di\u00e9 au secteur financier et dont l\u2019objectif est de renforcer la r\u00e9silience op\u00e9rationnelle num\u00e9rique. Contrairement \u00e0 une directive qui demande une transposition, un r\u00e8glement s\u2019applique en l\u2019\u00e9tat dans tous les pays de l\u2019union.<\/p>\n\n\n\n<p>Deux particularit\u00e9s sont \u00e0 relever dans ce r\u00e8glement. Premi\u00e8rement c\u2019est son obsession pour la s\u00e9curit\u00e9 de l\u2019information. Disponibilit\u00e9, authenticit\u00e9, int\u00e9grit\u00e9 et confidentialit\u00e9 sont les quatre crit\u00e8res qui reviennent de mani\u00e8re insistante dans le r\u00e8glement&nbsp;: dans la d\u00e9finition des \u00ab&nbsp;incidents op\u00e9rationnels&nbsp;\u00bb ou \u00ab&nbsp;li\u00e9s au TIC&nbsp;\u00bb de l&rsquo;article 3, puis dans la gouvernance et l\u2019organisation dans l&rsquo;article 5 ou encore dans l&rsquo;article 9 consacr\u00e9 \u00e0 la protection et pr\u00e9vention.<\/p>\n\n\n\n<p>Deuxi\u00e8mement, ce r\u00e8glement sectoriel concerne non seulement les assureurs et les \u00e9tablissements de cr\u00e9dit&nbsp;mais aussi leurs tiers prestataires de services&nbsp;informatiques (except\u00e9 les micro-entreprises). L\u2019article 28 du r\u00e8glement rappelle dans les principes g\u00e9n\u00e9raux que <em>\u00ab&nbsp;les entit\u00e9s financi\u00e8res qui ont conclu des accords contractuels pour l&rsquo;utilisation de services TIC dans le cadre de leurs activit\u00e9s restent \u00e0 tout moment pleinement responsables du respect et de l&rsquo;ex\u00e9cution de toutes les obligations d\u00e9coulant du pr\u00e9sent r\u00e8glement et du droit applicable aux services financiers<\/em>&nbsp;\u00bb. Impossible donc de rejeter la responsabilit\u00e9 sur un quelconque prestataire externe.<\/p>\n\n\n\n<p>Le paragraphe 5 de cet article indique ensuite que \u00ab&nbsp;<em>lorsque ces accords contractuels portent sur des fonctions critiques ou importantes, les entit\u00e9s financi\u00e8res prennent en consid\u00e9ration, avant la conclusion des accords, l&rsquo;utilisation par les prestataires tiers de services TIC des normes les plus actualis\u00e9es et les plus \u00e9lev\u00e9es en mati\u00e8re de s\u00e9curit\u00e9 de l&rsquo;information.<\/em>&nbsp;\u00bb Autrement dit, les prestataires de services IT critiques font partie int\u00e9grante de l\u2019\u00e9valuation des risques et les entit\u00e9s financi\u00e8res doivent s\u2019assurer de leur hygi\u00e8ne informatique.<\/p>\n\n\n\n<p>La r\u00e9flexion de l\u2019Union Europ\u00e9enne part du principe, av\u00e9r\u00e9 depuis les attaques comme celles de SolarWinds, qu\u2019un incident cyber peut se propager \u00e0 l\u2019ensemble des acteurs d\u2019un secteur. Il cherche donc \u00e0 pr\u00e9venir du risque d\u2019attaque de cha\u00eene d\u2019approvisionnement (Supply Chain).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>DORA renforce l&rsquo;usage du chiffrement<\/strong><\/strong><\/h2>\n\n\n\n<p>L\u2019article 9 \u00ab&nbsp;Protection et pr\u00e9vention&nbsp;\u00bb du r\u00e8glement impose d\u2019\u00e9laborer une politique de s\u00e9curit\u00e9 num\u00e9rique. Le paragraphe 2 du m\u00eame article pr\u00e9cise les dispositions \u00e0 prendre pour prot\u00e9ger les informations&nbsp;: \u00ab&nbsp;<em>les entit\u00e9s financi\u00e8res con\u00e7oivent, acqui\u00e8rent et mettent en \u0153uvre des strat\u00e9gies, des politiques, des proc\u00e9dures, des protocoles et des outils de s\u00e9curit\u00e9 de TIC qui visent \u00e0 garantir la r\u00e9silience, la continuit\u00e9 et la disponibilit\u00e9 des syst\u00e8mes de TIC, en particulier ceux qui soutiennent des fonctions critiques ou importantes, et \u00e0 maintenir des normes \u00e9lev\u00e9es en mati\u00e8re de disponibilit\u00e9, d&rsquo;authenticit\u00e9, d&rsquo;int\u00e9grit\u00e9 et de confidentialit\u00e9 des donn\u00e9es, que ce soit au repos, en cours d&rsquo;utilisation ou en transit<\/em>&nbsp;\u00bb. <\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" style=\"grid-template-columns:38% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"733\" src=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/12\/Chiffrement-03_Lite-1-1024x733.jpeg\" alt=\"\" class=\"wp-image-14644 size-full\" srcset=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/12\/Chiffrement-03_Lite-1-1024x733.jpeg 1024w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/12\/Chiffrement-03_Lite-1-300x215.jpeg 300w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/12\/Chiffrement-03_Lite-1-768x549.jpeg 768w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/12\/Chiffrement-03_Lite-1-100x72.jpeg 100w, https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/12\/Chiffrement-03_Lite-1.jpeg 1244w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Sans le nommer, c\u2019est bien le chiffrement des donn\u00e9es qui permet de r\u00e9pondre \u00e0 l\u2019obligation d\u2019authenticit\u00e9, d\u2019int\u00e9grit\u00e9 et de confidentialit\u00e9. <\/p>\n\n\n\n<p>On reconnait l\u00e0 \u00e9galement les trois avantages intrins\u00e8ques d\u2019une solution VPN qui permet sp\u00e9cifiquement de prot\u00e9ger ces donn\u00e9es quand elles sont \u00ab&nbsp;en cours d\u2019utilisation&nbsp;\u00bb, c\u2019est-\u00e0-dire quand un utilisateur souhaite acc\u00e9der au SI pour les consulter.<\/p>\n<\/div><\/div>\n\n\n\n<p>L\u2019article 30 impose que ces m\u00eames dispositions pour prot\u00e9ger les informations, soient prises par les \u00ab&nbsp;prestataires tiers de services TIC&nbsp;\u00bb. Elles doivent m\u00eame figurer dans les contrats qui r\u00e9gissent la relation afin de garantir \u00ab&nbsp;<em>la disponibilit\u00e9, l&rsquo;authenticit\u00e9, l&rsquo;int\u00e9grit\u00e9 et la confidentialit\u00e9 en ce qui concerne la protection des donn\u00e9es, y compris les donn\u00e9es \u00e0 caract\u00e8re personnel&nbsp;<\/em><em>\u00bb.<\/em><em><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong>Prot\u00e9ger les communications avec un VPN de confiance<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p>Comme pour la cybers\u00e9curit\u00e9, la confiance est un pilier du syst\u00e8me financier. On comprend alors mieux l\u2019obsession de DORA pour la disponibilit\u00e9, l\u2019int\u00e9grit\u00e9, authenticit\u00e9 et la confidentialit\u00e9 des donn\u00e9es. Etant donn\u00e9 l\u2019interconnexion des r\u00e9seaux, un incident interne ou externe remettant en cause l\u2019un de ces quatre principes, est de nature \u00e0 compromettre le syst\u00e8me financier.<\/p>\n\n\n\n<p>Les visas de s\u00e9curit\u00e9 de l\u2019ANSSI dont disposent les clients VPN TheGreenBow attestent de leur haut niveau de s\u00e9curit\u00e9. Leurs usages dans le secteur bancaire peuvent \u00eatre multiples&nbsp;: prot\u00e9ger les communications distantes des collaborateurs en t\u00e9l\u00e9travail, s\u00e9curiser les flux d\u2019administration gr\u00e2ce \u00e0 un&nbsp;<a href=\"https:\/\/www.thegreenbow.com\/fr\/cas-dusage-du-vpn\/diffusion-restreinte\/\" target=\"_blank\" rel=\"noreferrer noopener\">tunnel VPN IPsec<\/a>, maitriser les acc\u00e8s au SI octroy\u00e9s aux prestataires externes gr\u00e2ce \u00e0 des configurations sp\u00e9cifiques du client VPN \u2026<\/p>\n\n\n\n<p>Et pour faire face \u00e0 la menace quantique, TheGreenBow travaille d\u00e9j\u00e0 avec des grandes banques centrales sur des projets de d\u00e9ploiement de clients VPN int\u00e9grant des algorithmes de chiffrement r\u00e9sistants aux attaques quantiques.<\/p>\n\n\n\n<p>Avec une entr\u00e9e en application le 17 janvier 2025, il reste deux ans pour les acteurs du secteur financier et leurs prestataires informatiques pour se conformer au r\u00e8glement DORA. Ce qui n\u2019est pas de trop compte tenu de son niveau d\u2019exigence&nbsp;!<\/p>\n\n\n\n<p><\/p>\n\n\n\n  <section  class=\"wp-block-acf-linked-pages  section-content linked-pages-section\"  itemprop=\"hasPart\" itemscope itemtype=\"https:\/\/schema.org\/WebPageElement\">\n    <div class=\"grid-container\">\n     <div class=\"grid-x grid-padding-x align-center mobile-slider\">\n                <div class=\"cell medium-4 article\">\n            <div class=\"wrapper\">\n              \n                              <a  href=\"https:\/\/www.thegreenbow.com\/fr\/contact\/\" >\n\n                                          <figure>\n                        <img decoding=\"async\"  data-fade-in loading=\"lazy\" src=\"data:image\/png;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" data-lazy-interchange=\"[https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/11\/Discuter_lite-727x486.jpeg, small], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/11\/Discuter_lite-301x201.jpeg, medium], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/11\/Discuter_lite-343x229.jpeg, large], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/11\/Discuter_lite-1454x972.jpeg, retina], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/11\/Discuter_lite-602x402.jpeg, medium_retina], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/11\/Discuter_lite-686x458.jpeg, large_retina]\" data-interchange-sizes=\"{&quot;small&quot;:{&quot;w&quot;:727,&quot;h&quot;:486},&quot;medium&quot;:{&quot;w&quot;:301,&quot;h&quot;:201},&quot;large&quot;:{&quot;w&quot;:343,&quot;h&quot;:229},&quot;retina&quot;:{&quot;w&quot;:1454,&quot;h&quot;:972},&quot;medium_retina&quot;:{&quot;w&quot;:602,&quot;h&quot;:402},&quot;large_retina&quot;:{&quot;w&quot;:686,&quot;h&quot;:458}}\"  alt=\"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier\" itemprop=\"image\" data-fade-in \/>\n                      <\/figure>\n                    \n                                      <h4 class=\"block-title\">Un projet ? Discutons ensemble !<\/h4>\n                  \n                  \n                <\/a>\n              \n            <\/div>\n          <\/div>\n\n                  <div class=\"cell medium-4 article\">\n            <div class=\"wrapper\">\n              \n                              <a  href=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/ebook\/nis-2-et-dora-deux-reglementations-europeennes-necessaires-mais-ambitieuses\/\" >\n\n                                          <figure>\n                        <img decoding=\"async\"  data-fade-in loading=\"lazy\" src=\"data:image\/png;base64,R0lGODlhAQABAAD\/ACwAAAAAAQABAAACADs=\" data-lazy-interchange=\"[https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/07\/LB-NIS-2-DORA-593x396.png, small], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/07\/LB-NIS-2-DORA-301x201.png, medium], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/07\/LB-NIS-2-DORA-343x229.png, large], [https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2022\/07\/LB-NIS-2-DORA-593x396.png, retina]\" data-interchange-sizes=\"{&quot;small&quot;:{&quot;w&quot;:593,&quot;h&quot;:396},&quot;medium&quot;:{&quot;w&quot;:301,&quot;h&quot;:201},&quot;large&quot;:{&quot;w&quot;:343,&quot;h&quot;:229},&quot;retina&quot;:{&quot;w&quot;:593,&quot;h&quot;:396},&quot;medium_retina&quot;:{&quot;w&quot;:593,&quot;h&quot;:396},&quot;large_retina&quot;:{&quot;w&quot;:593,&quot;h&quot;:396}}\"  alt=\"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier\" itemprop=\"image\" data-fade-in \/>\n                      <\/figure>\n                    \n                                      <h4 class=\"block-title\">Livre Blanc : NIS2 et DORA<\/h4>\n                  \n                  \n                <\/a>\n              \n            <\/div>\n          <\/div>\n\n        \n\t\t<\/div>\n    <\/div>\n  <\/section>\n<\/div>\n","protected":false},"featured_media":14686,"template":"","meta":{"_acf_changed":false,"resource_type":"internal"},"resource_category":[30],"class_list":["post-14668","resource","type-resource","status-publish","has-post-thumbnail","hentry","resource_category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier - TheGreenBow<\/title>\n<meta name=\"description\" content=\"Le r\u00e9glement DORA publi\u00e9 au Journal Officiel de l&#039;UE : la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier et leurs prestataires informatiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier - TheGreenBow\" \/>\n<meta property=\"og:description\" content=\"Le r\u00e9glement DORA publi\u00e9 au Journal Officiel de l&#039;UE : la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier et leurs prestataires informatiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/\" \/>\n<meta property=\"og:site_name\" content=\"TheGreenBow\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-19T07:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Finance_lite.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1773\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@thegreenbow\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/\",\"name\":\"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier - TheGreenBow\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Finance_lite.jpeg\",\"datePublished\":\"2023-01-03T12:13:34+00:00\",\"dateModified\":\"2023-10-19T07:19:28+00:00\",\"description\":\"Le r\u00e9glement DORA publi\u00e9 au Journal Officiel de l'UE : la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier et leurs prestataires informatiques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Finance_lite.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Finance_lite.jpeg\",\"width\":1773,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressource\\\/blog\\\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/ressources\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/\",\"name\":\"TheGreenBow\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#organization\",\"name\":\"TheGreenBow\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logotype@2x-min.png\",\"contentUrl\":\"https:\\\/\\\/www.thegreenbow.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Logotype@2x-min.png\",\"width\":422,\"height\":84,\"caption\":\"TheGreenBow\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thegreenbow.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/thegreenbow\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/thegreenbow\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZKtI7_fmgFcmovgGSy8AnQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier - TheGreenBow","description":"Le r\u00e9glement DORA publi\u00e9 au Journal Officiel de l'UE : la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier et leurs prestataires informatiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier - TheGreenBow","og_description":"Le r\u00e9glement DORA publi\u00e9 au Journal Officiel de l'UE : la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier et leurs prestataires informatiques.","og_url":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/","og_site_name":"TheGreenBow","article_modified_time":"2023-10-19T07:19:28+00:00","og_image":[{"width":1773,"height":1182,"url":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Finance_lite.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@thegreenbow","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/","url":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/","name":"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier - TheGreenBow","isPartOf":{"@id":"https:\/\/www.thegreenbow.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/#primaryimage"},"image":{"@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Finance_lite.jpeg","datePublished":"2023-01-03T12:13:34+00:00","dateModified":"2023-10-19T07:19:28+00:00","description":"Le r\u00e9glement DORA publi\u00e9 au Journal Officiel de l'UE : la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier et leurs prestataires informatiques.","breadcrumb":{"@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/#primaryimage","url":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Finance_lite.jpeg","contentUrl":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2023\/01\/Finance_lite.jpeg","width":1773,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/www.thegreenbow.com\/fr\/ressource\/blog\/reglement-dora-quand-la-securite-des-donnees-devient-une-obsession-pour-le-secteur-financier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.thegreenbow.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/www.thegreenbow.com\/fr\/ressources\/blog\/"},{"@type":"ListItem","position":3,"name":"R\u00e8glement DORA\u00a0: quand\u00a0la s\u00e9curit\u00e9 des donn\u00e9es devient une obsession pour le secteur financier"}]},{"@type":"WebSite","@id":"https:\/\/www.thegreenbow.com\/fr\/#website","url":"https:\/\/www.thegreenbow.com\/fr\/","name":"TheGreenBow","description":"","publisher":{"@id":"https:\/\/www.thegreenbow.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thegreenbow.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.thegreenbow.com\/fr\/#organization","name":"TheGreenBow","url":"https:\/\/www.thegreenbow.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.thegreenbow.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/04\/Logotype@2x-min.png","contentUrl":"https:\/\/www.thegreenbow.com\/wp-content\/uploads\/2021\/04\/Logotype@2x-min.png","width":422,"height":84,"caption":"TheGreenBow"},"image":{"@id":"https:\/\/www.thegreenbow.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/thegreenbow","https:\/\/fr.linkedin.com\/company\/thegreenbow","https:\/\/www.youtube.com\/channel\/UCZKtI7_fmgFcmovgGSy8AnQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/resource\/14668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/media\/14686"}],"wp:attachment":[{"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/media?parent=14668"}],"wp:term":[{"taxonomy":"resource_category","embeddable":true,"href":"https:\/\/www.thegreenbow.com\/fr\/wp-json\/wp\/v2\/resource_category?post=14668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}